{"id":4494,"date":"2022-02-23T17:24:00","date_gmt":"2022-02-23T16:24:00","guid":{"rendered":"https:\/\/snudifo37.fr\/?p=4494"},"modified":"2022-02-26T17:27:05","modified_gmt":"2022-02-26T16:27:05","slug":"le-programme-de-macron-pour-lecole-en-finir-avec-le-statut-des-enseignants-pour-preparer-la-privatisation","status":"publish","type":"post","link":"https:\/\/snudifo37.fr\/index.php\/2022\/02\/23\/le-programme-de-macron-pour-lecole-en-finir-avec-le-statut-des-enseignants-pour-preparer-la-privatisation\/","title":{"rendered":"Le programme de Macron pour l\u2019Ecole : en finir avec le statut des enseignants pour pr\u00e9parer la privatisation"},"content":{"rendered":"\n<p>Des proches du pr\u00e9sident ont laiss\u00e9 fuiter dans les m\u00e9dias les mesures qu\u2019envisage de prendre Macron, s\u2019il est \u00e9lu en 2022 : fusion du minist\u00e8re de l\u2019Education nationale, de la Jeunesse et des Sports avec ceux de la Culture et de l\u2019Enseignement Sup\u00e9rieur et de la Recherche, suppression du CAPES, \u00ab fin du recrutement \u00e0 vie \u00bb dans l\u2019\u00c9ducation nationale. Les \u00e9quipes de Macron l\u00e2chent cette bombe un mois apr\u00e8s la gr\u00e8ve massive du 13 janvier et au moment o\u00f9 les personnels se mobilisent dans les d\u00e9partements face aux suppressions de postes et de classes pr\u00e9vues pour la rentr\u00e9e.<\/p>\n\n\n\n<p>Un responsable national de l\u2019UNSA cherche \u00e0 relativiser : <em>\u00ab cela ressemble \u00e0 une fake news \u00bb<\/em>. Pourtant, aucun d\u00e9menti n\u2019a \u00e9t\u00e9 apport\u00e9 par l\u2019Elys\u00e9e. Et pour cause, la politique men\u00e9e depuis 5 ans a d\u00e9montr\u00e9 que le \u00ab candidat \u00bb Macron sert d\u2019autres int\u00e9r\u00eats que celui de l\u2019Ecole publique et de ses personnels.<\/p>\n\n\n\n<h3 class=\"has-vivid-red-color has-text-color wp-block-heading\">Des mesures destin\u00e9es \u00e0 parachever les r\u00e9formes mises en \u0153uvre par Blanquer<\/h3>\n\n\n\n<p>Depuis 2021, le concours pour devenir professeur est repouss\u00e9 d\u2019un an, \u00e0 la fin de la deuxi\u00e8me ann\u00e9e de Master. Comme la Loi de Transformation de la Fonction publique, la r\u00e9forme Blanquer r\u00e9pond \u00e0 la logique gouvernementale qui consiste \u00e0 r\u00e9duire le nombre de fonctionnaires. Elle atteint cet objectif puisque les Master deuxi\u00e8me ann\u00e9e ne seront plus professeurs fonctionnaires mais \u00e9tudiants en alternance. Ce d\u00e9calage d\u2019un an repr\u00e9sente environ 9 000 fonctionnaires de moins et donc de substantielles \u00e9conomies \u00e0 la cl\u00e9. Des \u00e9tudiants qui se destinent \u00e0 l\u2019enseignement sont envoy\u00e9s seuls et sans formation dans des classes pour y enseigner 8h par semaine, pour un salaire d\u00e9risoire de 865 euros brut par mois\u2026<\/p>\n\n\n\n<h3 class=\"has-vivid-red-color has-text-color wp-block-heading\">Blanquer a privil\u00e9gi\u00e9 le recrutement contractuel tout au long du quinquennat<\/h3>\n\n\n\n<p>La baisse du nombre de postes aux concours, la pr\u00e9carisation grandissante et les contre-r\u00e9formes (en particulier la masterisation des concours) ont d\u00e9courag\u00e9 des milliers de candidats. En outre, les suppressions de postes ont conduit \u00e0 des fermetures de classes en cascades, \u00e0 l\u2019explosion des effectifs par classe et \u00e0 un manque criant de rempla\u00e7ants. Face \u00e0 cette p\u00e9nurie qui s\u2019est exacerb\u00e9e pendant la crise sanitaire, Blanquer, plut\u00f4t que de cr\u00e9er des postes statutaires, a eu recours \u00e0 des contractuels, moins chers et corv\u00e9ables \u00e0 merci. Et il a refus\u00e9 de r\u00e9pondre aux revendications des AESH mobilis\u00e9es pour un vrai statut et un vrai salaire\u2026<\/p>\n\n\n\n<h3 class=\"has-vivid-red-color has-text-color wp-block-heading\">Contractualiser, pour pr\u00e9parer la privatisation de l\u2019Ecole<\/h3>\n\n\n\n<p>La fin des concours ouvrirait la voie au recrutement local, dans la logique de l\u2019exp\u00e9rimentation marseillaise et des propositions du \u00ab Grenelle \u00bb de Blanquer. Celles-ci pr\u00e9voient de renforcer l\u2019autonomie des \u00e9coles et des \u00e9tablissements. Recrut\u00e9s en comme contractuels directement par les chefs d\u2019\u00e9tablissement ou les directeurs, les personnels seraient soumis \u00e0 toutes les pressions locales, politiques et \u00e9conomiques.<\/p>\n\n\n\n<p>La destruction du cadre national de l\u2019Ecole a constitu\u00e9 un premier front pour Macron et ses pr\u00e9d\u00e9cesseurs. Les r\u00e9formes du baccalaur\u00e9at et du lyc\u00e9e, la r\u00e9forme du coll\u00e8ge et les projets \u00e9ducatifs de territoire ont renforc\u00e9 l\u2019autonomie des \u00e9tablissements, les pla\u00e7ant en concurrence directe avec le priv\u00e9.<\/p>\n\n\n\n<p>Supprimer les concours signifierait la fin du recrutement statutaire. La fin des statuts nationaux, qui garantissent l\u2019ind\u00e9pendance des personnels, signifierait la fin de l\u2019Ecole publique et la\u00efque.<\/p>\n\n\n\n<p>Macron envisage d\u2019ailleurs de fusionner l\u2019\u00c9ducation nationale avec le minist\u00e8re de l\u2019Enseignement sup\u00e9rieur et celui de la Culture, o\u00f9 les logiques de territorialisation, de d\u00e9sengagement de l\u2019Etat et, finalement, de privatisation ont \u00e9galement \u00e9t\u00e9 engag\u00e9es depuis des ann\u00e9es. Apr\u00e8s la fusion avec le minist\u00e8re de la Jeunesse et des Sports, c\u2019est l\u2019existence m\u00eame de tous les statuts particuliers qui est en jeu.<\/p>\n\n\n\n<p>Face \u00e0 ce basculement, la FNEC FP-FO reste plus que jamais aux c\u00f4t\u00e9s des personnels qui ont fait gr\u00e8ve le 13 janvier contre le chaos provoqu\u00e9 par les mesures Macron-Blanquer. Cette gr\u00e8ve a impos\u00e9 un recul partiel au gouvernement qui a \u00e9t\u00e9 contraint de recruter la totalit\u00e9 des listes compl\u00e9mentaires dans le 1<sup>er<\/sup> degr\u00e9.<\/p>\n\n\n\n<h3 class=\"has-vivid-red-color has-text-color wp-block-heading\">Une br\u00e8che a \u00e9t\u00e9 ouverte, on peut les faire reculer !<\/h3>\n\n\n\n<p>La FNEC FP-FO soutient toutes les mobilisations en cours contre les suppressions de postes et de classes, pour un recrutement massif de personnels sous statut, pour de v\u00e9ritables augmentations de salaires, pour l\u2019arr\u00eat des contre-r\u00e9formes qui mettent \u00e0 mal les statuts et les conditions de travail, pour le r\u00e9tablissement du Baccalaur\u00e9at avec ses \u00e9preuves terminales et nationales.<\/p>\n\n\n\n<p class=\"has-text-align-right\"><em>Montreuil, le 23 f\u00e9vrier 2022<\/em><\/p>\n\n\n\n<div class=\"wp-block-file\"><a id=\"wp-block-file--media-72296239-864b-45a4-8358-08a60867d935\" href=\"https:\/\/snudifo37.fr\/wp-content\/uploads\/2022\/02\/22-02-23-le-programme-de-Macron-pour-lEcole-en-finir-avec-les-statuts.pdf\">22-02-23-le-programme-de-Macron-pour-lEcole-en-finir-avec-les-statuts<\/a><a href=\"https:\/\/snudifo37.fr\/wp-content\/uploads\/2022\/02\/22-02-23-le-programme-de-Macron-pour-lEcole-en-finir-avec-les-statuts.pdf\" class=\"wp-block-file__button\" download aria-describedby=\"wp-block-file--media-72296239-864b-45a4-8358-08a60867d935\">T\u00e9l\u00e9charger<\/a><\/div>\n<a class=\"synved-social-button synved-social-button-share synved-social-size-32 synved-social-resolution-single synved-social-provider-facebook nolightbox\" data-provider=\"facebook\" target=\"_blank\" rel=\"nofollow\" title=\"Faites le savoir \u00e0 vos amis via Facebook \" href=\"https:\/\/www.facebook.com\/sharer.php?u=https%3A%2F%2Fsnudifo37.fr%2Findex.php%2Fwp-json%2Fwp%2Fv2%2Fposts%2F4494&#038;t=Le%20programme%20de%20Macron%20pour%20l%E2%80%99Ecole%20%3A%20en%20finir%20avec%20le%20statut%20des%20enseignants%20pour%20pr%C3%A9parer%20la%20privatisation&#038;s=100&#038;p&#091;url&#093;=https%3A%2F%2Fsnudifo37.fr%2Findex.php%2Fwp-json%2Fwp%2Fv2%2Fposts%2F4494&#038;p&#091;images&#093;&#091;0&#093;=&#038;p&#091;title&#093;=Le%20programme%20de%20Macron%20pour%20l%E2%80%99Ecole%20%3A%20en%20finir%20avec%20le%20statut%20des%20enseignants%20pour%20pr%C3%A9parer%20la%20privatisation\" style=\"font-size: 0px;width:32px;height:32px;margin:0;margin-bottom:20px;margin-right:20px\"><img loading=\"lazy\" decoding=\"async\" alt=\"Facebook\" title=\"Faites le savoir \u00e0 vos amis via Facebook \" class=\"synved-share-image synved-social-image synved-social-image-share\" width=\"32\" height=\"32\" style=\"display: inline;width:32px;height:32px;margin: 0;padding: 0;border: none;box-shadow: none\" src=\"https:\/\/snudifo37.fr\/wp-content\/plugins\/social-media-feather\/synved-social\/image\/social\/regular\/64x64\/facebook.png\" \/><\/a><a class=\"synved-social-button synved-social-button-share synved-social-size-32 synved-social-resolution-single synved-social-provider-twitter nolightbox\" data-provider=\"twitter\" target=\"_blank\" rel=\"nofollow\" title=\"Informez-en vos amis via Twitter\" href=\"https:\/\/twitter.com\/intent\/tweet?url=https%3A%2F%2Fsnudifo37.fr%2Findex.php%2Fwp-json%2Fwp%2Fv2%2Fposts%2F4494&#038;text=Le%20Snudi-Fo%20vous%20informe%3A\" style=\"font-size: 0px;width:32px;height:32px;margin:0;margin-bottom:20px;margin-right:20px\"><img loading=\"lazy\" decoding=\"async\" alt=\"twitter\" title=\"Informez-en vos amis via Twitter\" class=\"synved-share-image synved-social-image synved-social-image-share\" width=\"32\" height=\"32\" style=\"display: inline;width:32px;height:32px;margin: 0;padding: 0;border: none;box-shadow: none\" src=\"https:\/\/snudifo37.fr\/wp-content\/plugins\/social-media-feather\/synved-social\/image\/social\/regular\/64x64\/twitter.png\" \/><\/a><a class=\"synved-social-button synved-social-button-share synved-social-size-32 synved-social-resolution-single synved-social-provider-mail nolightbox\" data-provider=\"mail\" rel=\"nofollow\" title=\"Les derni\u00e8res informations du Snudi-Fo 37\" href=\"mailto:?subject=Le%20programme%20de%20Macron%20pour%20l%E2%80%99Ecole%20%3A%20en%20finir%20avec%20le%20statut%20des%20enseignants%20pour%20pr%C3%A9parer%20la%20privatisation&#038;body=Le%20Snudi-Fo%20vous%20informe%3A:%20https%3A%2F%2Fsnudifo37.fr%2Findex.php%2Fwp-json%2Fwp%2Fv2%2Fposts%2F4494\" style=\"font-size: 0px;width:32px;height:32px;margin:0;margin-bottom:20px\"><img loading=\"lazy\" decoding=\"async\" alt=\"mail\" title=\"Les derni\u00e8res informations du Snudi-Fo 37\" class=\"synved-share-image synved-social-image synved-social-image-share\" width=\"32\" height=\"32\" style=\"display: inline;width:32px;height:32px;margin: 0;padding: 0;border: none;box-shadow: none\" src=\"https:\/\/snudifo37.fr\/wp-content\/plugins\/social-media-feather\/synved-social\/image\/social\/regular\/64x64\/mail.png\" \/><\/a>","protected":false},"excerpt":{"rendered":"<p>Des proches du pr\u00e9sident ont laiss\u00e9 fuiter dans les m\u00e9dias les mesures qu\u2019envisage de prendre Macron, s\u2019il est \u00e9lu en 2022 : fusion du minist\u00e8re de l\u2019Education nationale, de la Jeunesse et des Sports avec ceux de la Culture et de l\u2019Enseignement Sup\u00e9rieur et de la Recherche, suppression du CAPES, \u00ab fin du recrutement \u00e0 vie \u00bb dans l\u2019\u00c9ducation nationale. Les \u00e9quipes de Macron l\u00e2chent cette bombe un mois apr\u00e8s la gr\u00e8ve massive du 13 janvier et au moment o\u00f9 les personnels se mobilisent dans les d\u00e9partements face aux suppressions de postes et de classes pr\u00e9vues pour la rentr\u00e9e.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[1179,34,1231,1014,169,673,1230,178],"class_list":["post-4494","post","type-post","status-publish","format-standard","hentry","category-syndicat","tag-1179","tag-blanquer","tag-contractualiser","tag-ecole-2","tag-macron","tag-privatisation","tag-programme","tag-statut"],"_links":{"self":[{"href":"https:\/\/snudifo37.fr\/index.php\/wp-json\/wp\/v2\/posts\/4494","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/snudifo37.fr\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/snudifo37.fr\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/snudifo37.fr\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/snudifo37.fr\/index.php\/wp-json\/wp\/v2\/comments?post=4494"}],"version-history":[{"count":2,"href":"https:\/\/snudifo37.fr\/index.php\/wp-json\/wp\/v2\/posts\/4494\/revisions"}],"predecessor-version":[{"id":4523,"href":"https:\/\/snudifo37.fr\/index.php\/wp-json\/wp\/v2\/posts\/4494\/revisions\/4523"}],"wp:attachment":[{"href":"https:\/\/snudifo37.fr\/index.php\/wp-json\/wp\/v2\/media?parent=4494"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/snudifo37.fr\/index.php\/wp-json\/wp\/v2\/categories?post=4494"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/snudifo37.fr\/index.php\/wp-json\/wp\/v2\/tags?post=4494"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}