{"id":1185,"date":"2019-12-06T07:30:00","date_gmt":"2019-12-06T06:30:00","guid":{"rendered":"http:\/\/snudifo37.fr\/?p=1185"},"modified":"2019-12-06T22:43:40","modified_gmt":"2019-12-06T21:43:40","slug":"greve-du-5-decembre-proposition-de-lettre-aux-parents","status":"publish","type":"post","link":"https:\/\/snudifo37.fr\/index.php\/2019\/12\/06\/greve-du-5-decembre-proposition-de-lettre-aux-parents\/","title":{"rendered":"Gr\u00e8ve du 5 d\u00e9cembre: proposition de lettre aux parents [MAJ]"},"content":{"rendered":"\n<p><em>[<\/em><strong>Mise \u00e0 jour:<\/strong> <em>Nous proposons aux coll\u00e8gues un mod\u00e8le de mot destin\u00e9 au cahier des \u00e9l\u00e8ves pour leur signaler leur absence, et la possible reconduite du mouvement. Voir en bas de la page.]<\/em><\/p>\n\n\n\n<p>Beaucoup de coll\u00e8gues nous interrogent sur le discours \u00e0 tenir aux parents concernant cette gr\u00e8ve reconductible. <strong>Il est n\u00e9cessaire \u00e0 ce sujet de faire preuve de prudence,<\/strong> en raison de notre devoir de neutralit\u00e9 envers notre public, mais aussi avec l&rsquo;adoption r\u00e9cente de l&rsquo;article sur l&rsquo;exemplarit\u00e9 des enseignants de la Loi Blanquer et l&rsquo;application de plus en plus large et \u00e0 charge des protocoles PPCR.<\/p>\n\n\n\n<p>Pour autant, il est important d&rsquo;informer sur les raisons de cette gr\u00e8ve et sur les cons\u00e9quences de la r\u00e9forme des retraites si elle devait \u00eatre adopt\u00e9e. <\/p>\n\n\n\n<p><strong>Ce point est d&rsquo;autant plus vrai que les parents d&rsquo;\u00e9l\u00e8ves ne sont pas nos adversaires<\/strong>. Au contraire: pour beaucoup, ce sont des travailleurs, des salari\u00e9s, des employ\u00e9s qui souffriront eux aussi des cons\u00e9quences n\u00e9gatives \u00e0 venir de cette r\u00e9forme. <strong>Les informer sur les raisons de cette gr\u00e8ve, c&rsquo;est aussi les informer sur les menaces qui planent sur eux, leur futur et celui de leurs enfants.<\/strong><\/p>\n\n\n\n<p>C&rsquo;est pourquoi le Snudi-FO propose un mod\u00e8le de lettre dont les coll\u00e8gues peuvent se servir ou s&rsquo;inspirer pour avertir les parents d&rsquo;\u00e9l\u00e8ves. <\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Mais des pr\u00e9cautions s&rsquo;imposent !<\/strong><\/h3>\n\n\n\n<p class=\"has-text-color has-background has-very-light-gray-color has-vivid-red-background-color\"><strong>Il est en effet tr\u00e8s important que cette lettre (ou tout autre document concernant ce mouvement social) ne soit pas coll\u00e9e dans les cahiers des \u00e9l\u00e8ves ! <\/strong><\/p>\n\n\n\n<p><strong>L&rsquo;id\u00e9al serait de la mettre dans une enveloppe ferm\u00e9e, ou de la plier et de l&rsquo;agrafer (sans qu&rsquo;elle le soit au cahier) <\/strong>afin qu&rsquo;elle ne soit pas lue imm\u00e9diatement, et qu&rsquo;elle soit conserv\u00e9e ou jet\u00e9e par les parents d&rsquo;\u00e9l\u00e8ves une fois \u00e0 leur domicile.<\/p>\n\n\n\n<p>Encore une fois, nous insistons lourdement: <strong>NE LA COLLEZ PAS OU NE L&rsquo;ACCROCHEZ PAS DANS LES CAHIERS DE LIAISON et pr\u00e9cisez qu&rsquo;il s&rsquo;agit d&rsquo;une information aux parents, et non un mot qu&rsquo;il est n\u00e9cessaire de vous retourner sign\u00e9.<\/strong> Ne le signez pas de votre nom non plus, n&rsquo;indiquez pas le nom ou l&rsquo;adresse de l&rsquo;\u00e9tablissement concern\u00e9.<\/p>\n\n\n\n<h3 class=\"has-vivid-red-color has-text-color has-text-align-center wp-block-heading\"><strong>Proposition de lettre aux parents:<\/strong><\/h3>\n\n\n\n<p><em>Chers parents,<\/em><\/p>\n\n\n\n<p><em>La situation dans les \u00e9coles ne cesse de se d\u00e9grader depuis des ann\u00e9es. La manque de postes aboutit \u00e0 des classes toujours plus charg\u00e9es, les rempla\u00e7ants et les enseignants sp\u00e9cialis\u00e9s manquent, l\u2019inclusion de nombreux \u00e9l\u00e8ves en difficult\u00e9 ou en situation de handicap se passe dans des conditions inacceptables\u2026<\/em><\/p>\n\n\n\n<p><em>Nombre d\u2019enseignants sont aujourd\u2019hui \u00e0 bout, ce qui d\u2019ailleurs a pu conduire notre coll\u00e8gue Christine Renon, directrice d\u2019\u00e9cole \u00e0 Pantin, \u00e0 commettre l\u2019irr\u00e9parable.<\/em><\/p>\n\n\n\n<p><em>C\u2019est dans cette situation que le gouvernement a pr\u00e9sent\u00e9 son projet de r\u00e9forme des retraites qui consiste \u00e0 instaurer un r\u00e9gime universel par points en supprimant les r\u00e9gimes existants.<\/em><\/p>\n\n\n\n<p><em>Cela lui permettrait chaque ann\u00e9e de baisser la valeur du point et donc le montant des retraites de tous les salari\u00e9s. Un tel syst\u00e8me a \u00e9t\u00e9 mis en place en Su\u00e8de en 1998. Une \u00e9tude parue en mars 2017 a montr\u00e9 que 92% des Su\u00e9doises auraient eu des retraites sup\u00e9rieures dans l\u2019ancien syst\u00e8me et 72 % des hommes (Source : Lib\u00e9ration, 12 octobre 2019)<\/em><\/p>\n\n\n\n<p><em>Tous les salari\u00e9s seraient perdants avec ce r\u00e9gime unique, qui prendrait en compte toute la carri\u00e8re pour le calcul de la retraite et non les meilleures ann\u00e9es ou les derniers mois. Les enseignants pourraient ainsi voir leurs pensions baisser jusqu\u2019\u00e0 40% !<\/em><\/p>\n\n\n\n<p><em>Cette r\u00e9forme suscite un rejet dans de nombreux secteurs professionnels qui entendent se mettre en gr\u00e8ve reconductible \u00e0 partir du 5 d\u00e9cembre pour en exiger le retrait : RATP, SNCF, S\u00e9curit\u00e9 Sociale, Air France, h\u00f4pitaux, chimie\u2026<\/em><\/p>\n\n\n\n<p><em>Dans l\u2019enseignement, nos organisations syndicales FO, FSU, CGT, SUD, SNALC et CNT appellent \u00e9galement \u00e0 la gr\u00e8ve d\u00e8s le jeudi 5 d\u00e9cembre.<\/em><\/p>\n\n\n\n<p><em>Nous vous informons que nous rejoignons ce grand mouvement social qui se dessine \u00e0 compter du 5 d\u00e9cembre.<\/em><\/p>\n\n\n\n<p><em>Nous sommes persuad\u00e9s que, unis, les salari\u00e9s du public et du priv\u00e9 pourront faire \u00e9chec \u00e0 cette r\u00e9forme qui menacerait le montant de nos pensions et nous contraindrait par la m\u00eame \u00e0 travailler bien plus longtemps pour b\u00e9n\u00e9ficier d\u2019une retraite acceptable.<\/em><\/p>\n\n\n\n<div class=\"wp-block-file\"><a href=\"http:\/\/snudifo37.fr\/wp-content\/uploads\/2019\/11\/mots_parents.pdf\">Proposition de mot aux parents<\/a><a href=\"http:\/\/snudifo37.fr\/wp-content\/uploads\/2019\/11\/mots_parents.pdf\" class=\"wp-block-file__button\" download>T\u00e9l\u00e9charger<\/a><\/div>\n\n\n\n<h3 class=\"has-vivid-red-color has-text-color has-text-align-center wp-block-heading\">Mot \u00e0 coller dans les cahiers de liaison<\/h3>\n\n\n\n<p><em>A&nbsp; ,<\/em><\/p>\n\n\n\n<p><em>Le&nbsp;&nbsp;&nbsp; ,<\/em><\/p>\n\n\n\n<p><em>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Chers parents,<\/em><\/p>\n\n\n\n<p><em>Nous tenons \u00e0 vous informer que nous serons en gr\u00e8ve le 5 d\u00e9cembre prochain. La classe ne sera donc pas assur\u00e9e ce jour l\u00e0. Il est possible que ce mouvement de gr\u00e8ve se poursuive. Nous vous tiendrons alors inform\u00e9s de la situation.<\/em><\/p>\n\n\n\n<p class=\"has-text-align-right\"><em>Bien cordialement,<\/em><\/p>\n\n\n\n<p class=\"has-text-align-right\"><em>L&rsquo;\u00e9quipe enseignante<\/em><\/p>\n\n\n\n<div class=\"wp-block-file\"><a href=\"http:\/\/snudifo37.fr\/wp-content\/uploads\/2019\/11\/info-gr\u00e8ve-reconductible.odt\">info-gr\u00e8ve-reconductible<\/a><a href=\"http:\/\/snudifo37.fr\/wp-content\/uploads\/2019\/11\/info-gr\u00e8ve-reconductible.odt\" class=\"wp-block-file__button\" download>T\u00e9l\u00e9charger<\/a><\/div>\n<a class=\"synved-social-button synved-social-button-share synved-social-size-32 synved-social-resolution-single synved-social-provider-facebook nolightbox\" data-provider=\"facebook\" target=\"_blank\" rel=\"nofollow\" title=\"Faites le savoir \u00e0 vos amis via Facebook \" href=\"https:\/\/www.facebook.com\/sharer.php?u=https%3A%2F%2Fsnudifo37.fr%2Findex.php%2Fwp-json%2Fwp%2Fv2%2Fposts%2F1185&#038;t=Gr%C3%A8ve%20du%205%20d%C3%A9cembre%3A%20proposition%20de%20lettre%20aux%20parents%20%5BMAJ%5D&#038;s=100&#038;p&#091;url&#093;=https%3A%2F%2Fsnudifo37.fr%2Findex.php%2Fwp-json%2Fwp%2Fv2%2Fposts%2F1185&#038;p&#091;images&#093;&#091;0&#093;=&#038;p&#091;title&#093;=Gr%C3%A8ve%20du%205%20d%C3%A9cembre%3A%20proposition%20de%20lettre%20aux%20parents%20%5BMAJ%5D\" style=\"font-size: 0px;width:32px;height:32px;margin:0;margin-bottom:20px;margin-right:20px\"><img loading=\"lazy\" decoding=\"async\" alt=\"Facebook\" title=\"Faites le savoir \u00e0 vos amis via Facebook \" class=\"synved-share-image synved-social-image synved-social-image-share\" width=\"32\" height=\"32\" style=\"display: inline;width:32px;height:32px;margin: 0;padding: 0;border: none;box-shadow: none\" src=\"https:\/\/snudifo37.fr\/wp-content\/plugins\/social-media-feather\/synved-social\/image\/social\/regular\/64x64\/facebook.png\" \/><\/a><a class=\"synved-social-button synved-social-button-share synved-social-size-32 synved-social-resolution-single synved-social-provider-twitter nolightbox\" data-provider=\"twitter\" target=\"_blank\" rel=\"nofollow\" title=\"Informez-en vos amis via Twitter\" href=\"https:\/\/twitter.com\/intent\/tweet?url=https%3A%2F%2Fsnudifo37.fr%2Findex.php%2Fwp-json%2Fwp%2Fv2%2Fposts%2F1185&#038;text=Le%20Snudi-Fo%20vous%20informe%3A\" style=\"font-size: 0px;width:32px;height:32px;margin:0;margin-bottom:20px;margin-right:20px\"><img loading=\"lazy\" decoding=\"async\" alt=\"twitter\" title=\"Informez-en vos amis via Twitter\" class=\"synved-share-image synved-social-image synved-social-image-share\" width=\"32\" height=\"32\" style=\"display: inline;width:32px;height:32px;margin: 0;padding: 0;border: none;box-shadow: none\" src=\"https:\/\/snudifo37.fr\/wp-content\/plugins\/social-media-feather\/synved-social\/image\/social\/regular\/64x64\/twitter.png\" \/><\/a><a class=\"synved-social-button synved-social-button-share synved-social-size-32 synved-social-resolution-single synved-social-provider-mail nolightbox\" data-provider=\"mail\" rel=\"nofollow\" title=\"Les derni\u00e8res informations du Snudi-Fo 37\" href=\"mailto:?subject=Gr%C3%A8ve%20du%205%20d%C3%A9cembre%3A%20proposition%20de%20lettre%20aux%20parents%20%5BMAJ%5D&#038;body=Le%20Snudi-Fo%20vous%20informe%3A:%20https%3A%2F%2Fsnudifo37.fr%2Findex.php%2Fwp-json%2Fwp%2Fv2%2Fposts%2F1185\" style=\"font-size: 0px;width:32px;height:32px;margin:0;margin-bottom:20px\"><img loading=\"lazy\" decoding=\"async\" alt=\"mail\" title=\"Les derni\u00e8res informations du Snudi-Fo 37\" class=\"synved-share-image synved-social-image synved-social-image-share\" width=\"32\" height=\"32\" style=\"display: inline;width:32px;height:32px;margin: 0;padding: 0;border: none;box-shadow: none\" src=\"https:\/\/snudifo37.fr\/wp-content\/plugins\/social-media-feather\/synved-social\/image\/social\/regular\/64x64\/mail.png\" \/><\/a>","protected":false},"excerpt":{"rendered":"<p>Afin d&rsquo;informer sur le mouvement social du 5 d\u00e9cembre, le Snudi-FO vous invite \u00e0 consulter sa proposition de lettre aux parents d&rsquo;\u00e9l\u00e8ves.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[22,226,225,269,90,273,105,274],"class_list":["post-1185","post","type-post","status-publish","format-standard","hentry","category-syndicat","tag-22","tag-5-decembre","tag-greve","tag-greve-reconductible","tag-information","tag-lettre","tag-parents","tag-proposition"],"_links":{"self":[{"href":"https:\/\/snudifo37.fr\/index.php\/wp-json\/wp\/v2\/posts\/1185","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/snudifo37.fr\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/snudifo37.fr\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/snudifo37.fr\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/snudifo37.fr\/index.php\/wp-json\/wp\/v2\/comments?post=1185"}],"version-history":[{"count":5,"href":"https:\/\/snudifo37.fr\/index.php\/wp-json\/wp\/v2\/posts\/1185\/revisions"}],"predecessor-version":[{"id":1311,"href":"https:\/\/snudifo37.fr\/index.php\/wp-json\/wp\/v2\/posts\/1185\/revisions\/1311"}],"wp:attachment":[{"href":"https:\/\/snudifo37.fr\/index.php\/wp-json\/wp\/v2\/media?parent=1185"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/snudifo37.fr\/index.php\/wp-json\/wp\/v2\/categories?post=1185"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/snudifo37.fr\/index.php\/wp-json\/wp\/v2\/tags?post=1185"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}